{"id":6613,"date":"2023-05-16T12:43:37","date_gmt":"2023-05-16T10:43:37","guid":{"rendered":"http:\/\/www.laperle.tess5418.odns.fr\/vida-nocturna\/"},"modified":"2024-10-17T21:59:40","modified_gmt":"2024-10-17T19:59:40","slug":"vida-nocturna","status":"publish","type":"page","link":"https:\/\/www.hoteldenotredame.com\/es\/visite-paris\/vida-nocturna\/","title":{"rendered":"Vida nocturna"},"content":{"rendered":"\n<p class=\"has-text-align-justify wp-block-paragraph\">Descubre la encantadora vida nocturna de la Orilla Izquierda de Par\u00eds. Este barrio hist\u00f3rico cobra vida al anochecer con sus caf\u00e9s, acogedoras vinotecas y animados clubes de jazz. Sum\u00e9rgete en el ambiente bohemio, saboreando deliciosos c\u00f3cteles, m\u00fasica en directo y veladas inolvidables en uno de los barrios m\u00e1s emblem\u00e1ticos de la ciudad.<\/p>\n\n<div class=\"wp-block-query is-layout-flow wp-block-query-is-layout-flow\"><ul class=\"columns-3 wp-block-post-template is-layout-grid wp-container-core-post-template-is-layout-0d5c60d9 wp-block-post-template-is-layout-grid\"><li class=\"wp-block-post post-8636 post type-post status-publish format-standard has-post-thumbnail hentry category-vida-nocturna-es\">\n<figure class=\"bordure-doree image-zoom wp-block-post-featured-image\"><a href=\"https:\/\/www.hoteldenotredame.com\/es\/vida-nocturna-es\/fubar\/\" target=\"_self\" ><img decoding=\"async\" width=\"344\" height=\"173\" src=\"https:\/\/www.hoteldenotredame.com\/wp-content\/uploads\/2024\/09\/long-hope-petit.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"The Long Hope\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.hoteldenotredame.com\/wp-content\/uploads\/2024\/09\/long-hope-petit.jpg 344w, https:\/\/www.hoteldenotredame.com\/wp-content\/uploads\/2024\/09\/long-hope-petit-300x151.jpg 300w\" sizes=\"(max-width: 344px) 100vw, 344px\" title=\"\"><\/a><\/figure>\n\n<h2 class=\"has-text-align-center has-link-color wp-elements-1 wp-block-post-title has-medium-font-size\"><a href=\"https:\/\/www.hoteldenotredame.com\/es\/vida-nocturna-es\/fubar\/\" target=\"_self\" >The Long Hope<\/a><\/h2>\n<\/li><li class=\"wp-block-post post-8990 post type-post status-publish format-standard has-post-thumbnail hentry category-vida-nocturna-es\">\n<figure class=\"bordure-doree image-zoom wp-block-post-featured-image\"><a href=\"https:\/\/www.hoteldenotredame.com\/es\/vida-nocturna-es\/la-prescription\/\" target=\"_self\" ><img decoding=\"async\" width=\"344\" height=\"173\" src=\"https:\/\/www.hoteldenotredame.com\/wp-content\/uploads\/2024\/09\/Le-noddi-petit.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Le Noddi\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.hoteldenotredame.com\/wp-content\/uploads\/2024\/09\/Le-noddi-petit.jpg 344w, https:\/\/www.hoteldenotredame.com\/wp-content\/uploads\/2024\/09\/Le-noddi-petit-300x151.jpg 300w\" sizes=\"(max-width: 344px) 100vw, 344px\" title=\"\"><\/a><\/figure>\n\n<h2 class=\"has-text-align-center has-link-color wp-elements-2 wp-block-post-title has-medium-font-size\"><a href=\"https:\/\/www.hoteldenotredame.com\/es\/vida-nocturna-es\/la-prescription\/\" target=\"_self\" >Le Noddi<\/a><\/h2>\n<\/li><li class=\"wp-block-post post-9006 post type-post status-publish format-standard has-post-thumbnail hentry category-vida-nocturna-es\">\n<figure class=\"bordure-doree image-zoom wp-block-post-featured-image\"><a href=\"https:\/\/www.hoteldenotredame.com\/es\/vida-nocturna-es\/rue-guisarde-and-rue-des-canettes\/\" target=\"_self\" ><img decoding=\"async\" width=\"325\" height=\"173\" src=\"https:\/\/www.hoteldenotredame.com\/wp-content\/uploads\/2016\/05\/le-paradis-latin-in-paris-petit-1.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Le Paradis Latin\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.hoteldenotredame.com\/wp-content\/uploads\/2016\/05\/le-paradis-latin-in-paris-petit-1.jpg 325w, https:\/\/www.hoteldenotredame.com\/wp-content\/uploads\/2016\/05\/le-paradis-latin-in-paris-petit-1-300x160.jpg 300w\" sizes=\"(max-width: 325px) 100vw, 325px\" title=\"\"><\/a><\/figure>\n\n<h2 class=\"has-text-align-center has-link-color wp-elements-3 wp-block-post-title has-medium-font-size\"><a href=\"https:\/\/www.hoteldenotredame.com\/es\/vida-nocturna-es\/rue-guisarde-and-rue-des-canettes\/\" target=\"_self\" >Le Paradis Latin<\/a><\/h2>\n<\/li><li class=\"wp-block-post post-9023 post type-post status-publish format-standard has-post-thumbnail hentry category-vida-nocturna-es\">\n<figure class=\"bordure-doree image-zoom wp-block-post-featured-image\"><a href=\"https:\/\/www.hoteldenotredame.com\/es\/vida-nocturna-es\/chez-georges\/\" target=\"_self\" ><img decoding=\"async\" width=\"344\" height=\"173\" src=\"https:\/\/www.hoteldenotredame.com\/wp-content\/uploads\/2024\/09\/aux-trois-mailletz-petit.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Aux Trois Mailletz\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.hoteldenotredame.com\/wp-content\/uploads\/2024\/09\/aux-trois-mailletz-petit.jpg 344w, https:\/\/www.hoteldenotredame.com\/wp-content\/uploads\/2024\/09\/aux-trois-mailletz-petit-300x151.jpg 300w\" sizes=\"(max-width: 344px) 100vw, 344px\" title=\"\"><\/a><\/figure>\n\n<h2 class=\"has-text-align-center has-link-color wp-elements-4 wp-block-post-title has-medium-font-size\"><a href=\"https:\/\/www.hoteldenotredame.com\/es\/vida-nocturna-es\/chez-georges\/\" target=\"_self\" >Aux Trois Mailletz<\/a><\/h2>\n<\/li><li class=\"wp-block-post post-9037 post type-post status-publish format-standard has-post-thumbnail hentry category-vida-nocturna-es\">\n<figure class=\"bordure-doree image-zoom wp-block-post-featured-image\"><a href=\"https:\/\/www.hoteldenotredame.com\/es\/vida-nocturna-es\/ducs-des-lombards\/\" target=\"_self\" ><img decoding=\"async\" width=\"344\" height=\"173\" src=\"https:\/\/www.hoteldenotredame.com\/wp-content\/uploads\/2023\/10\/Hotel-in-Paris-Night-Life-Ducs-des-Lombards-jpg.webp\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Ducs des Lombards\" style=\"object-fit:cover;\" title=\"\"><\/a><\/figure>\n\n<h2 class=\"has-text-align-center has-link-color wp-elements-5 wp-block-post-title has-medium-font-size\"><a href=\"https:\/\/www.hoteldenotredame.com\/es\/vida-nocturna-es\/ducs-des-lombards\/\" target=\"_self\" >Ducs des Lombards<\/a><\/h2>\n<\/li><li class=\"wp-block-post post-9053 post type-post status-publish format-standard has-post-thumbnail hentry category-vida-nocturna-es\">\n<figure class=\"bordure-doree image-zoom wp-block-post-featured-image\"><a href=\"https:\/\/www.hoteldenotredame.com\/es\/vida-nocturna-es\/le-caveau-de-la-huchette\/\" target=\"_self\" ><img decoding=\"async\" width=\"344\" height=\"173\" src=\"https:\/\/www.hoteldenotredame.com\/wp-content\/uploads\/2023\/10\/Hotel-in-Paris-Night-Life-Caveau-de-la-Huchette-jpg.webp\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Le Caveau de la Huchette\" style=\"object-fit:cover;\" title=\"\"><\/a><\/figure>\n\n<h2 class=\"has-text-align-center has-link-color wp-elements-6 wp-block-post-title has-medium-font-size\"><a href=\"https:\/\/www.hoteldenotredame.com\/es\/vida-nocturna-es\/le-caveau-de-la-huchette\/\" target=\"_self\" >Le Caveau de la Huchette<\/a><\/h2>\n<\/li><\/ul>\n\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Descubre la encantadora vida nocturna de la Orilla Izquierda de Par\u00eds. Este barrio hist\u00f3rico cobra vida al anochecer con sus caf\u00e9s, acogedoras vinotecas y animados clubes de jazz. Sum\u00e9rgete en el ambiente bohemio, saboreando deliciosos c\u00f3cteles, m\u00fasica en directo y veladas inolvidables en uno de los barrios m\u00e1s emblem\u00e1ticos de la ciudad.<\/p>\n","protected":false},"author":1,"featured_media":15601,"parent":6656,"menu_order":6,"comment_status":"closed","ping_status":"closed","template":"wp-custom-template-le-template-des-pages-2023","meta":{"footnotes":""},"class_list":["post-6613","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.hoteldenotredame.com\/es\/wp-json\/wp\/v2\/pages\/6613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hoteldenotredame.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hoteldenotredame.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hoteldenotredame.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hoteldenotredame.com\/es\/wp-json\/wp\/v2\/comments?post=6613"}],"version-history":[{"count":2,"href":"https:\/\/www.hoteldenotredame.com\/es\/wp-json\/wp\/v2\/pages\/6613\/revisions"}],"predecessor-version":[{"id":20916,"href":"https:\/\/www.hoteldenotredame.com\/es\/wp-json\/wp\/v2\/pages\/6613\/revisions\/20916"}],"up":[{"embeddable":true,"href":"https:\/\/www.hoteldenotredame.com\/es\/wp-json\/wp\/v2\/pages\/6656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hoteldenotredame.com\/es\/wp-json\/wp\/v2\/media\/15601"}],"wp:attachment":[{"href":"https:\/\/www.hoteldenotredame.com\/es\/wp-json\/wp\/v2\/media?parent=6613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}